{"id":19491,"date":"2022-06-27T10:44:41","date_gmt":"2022-06-27T08:44:41","guid":{"rendered":"https:\/\/www.anicecommunication.com\/it\/?p=19491"},"modified":"2026-06-16T12:19:35","modified_gmt":"2026-06-16T10:19:35","slug":"apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket","status":"publish","type":"post","link":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/","title":{"rendered":"Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &#038; Rocket"},"content":{"rendered":"<ul>\n<li><strong>Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &amp; Rocket, volto a promuovere l&#8217;uguaglianza attraverso l&#8217;istruzione<\/strong><\/li>\n<\/ul>\n<p><!--more--><\/p>\n<p><strong>Amsterdam, 27 giugno 2022<\/strong> \u2013 A inizio mese, Apollo Tyres ha sponsorizzato e organizzato una &#8220;Tire Masterclass&#8221; in occasione del &#8220;Cash &amp; Rocket 2022 Sustainable Tour&#8221;, un evento di beneficenza che ha come scopo la raccolta di fondi per donne e bambini bisognosi e promuove l&#8217;uguaglianza di genere attraverso l&#8217;istruzione.<\/p>\n<p>Il tour \u00e8 durato quattro giorni, dal 9 al 12 giugno, e ha visto la partecipazione di 80 donne, che hanno raccolto oltre 437.000 \u20ac a favore di una serie di organizzazioni benefiche, tra cui Sumbandila, Helen Bamber Foundation e Croce Rossa spagnola. Apollo Tyres, la prima azienda produttrice di pneumatici a sponsorizzare questo evento, ha fatto bella mostra del suo marchio di prodotti premium, Vredestein, sulle vetture che hanno partecipato al tour e sulla segnaletica dell&#8217;evento.<\/p>\n<p><a href=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-19493\" src=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg\" alt=\"Apollo Tyres sostiene Cash &amp; Rocket\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-200x133.jpg 200w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-300x200.jpg 300w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-400x267.jpg 400w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-600x400.jpg 600w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-768x512.jpg 768w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-800x533.jpg 800w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-1024x683.jpg 1024w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-1200x800.jpg 1200w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito-1536x1024.jpg 1536w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg 1800w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/p>\n<p>Questo \u00e8 stato il primo anno in cui tutte le 40 auto del Cash &amp; Rocket Sustainable Tour, caratterizzate da una livrea rossa con marchio Vredestein, erano veicoli ibridi o elettrici. Il percorso, con partenza nel cuore di Barcellona, in Spagna, ha visto le squadre guidare lungo le strade della Provenza, di Milano fino a raggiungere Firenze.<\/p>\n<p>Durante il tour, Apollo Tyres ha organizzato una presentazione presso Chateau Roquelune, in Francia, tenuta dalla madrina dell\u2019evento, Yvette Houtgraaf (nota anche come Het AutoMeisje, La Ragazza dell\u2019Auto), influencer olandese del settore automobilistico. Alle partecipanti sono state illustrate le diverse caratteristiche degli pneumatici specifici per tutte le stagioni, con una particolare attenzione per la pluripremiata gamma Vredestein di pneumatici invernali, estivi e all-season. Apollo Tyres ha inoltre collaborato con il rivenditore francese di pneumatici Allopneus per una dimostrazione di come sostituire uno pneumatico.<\/p>\n<p>Il team Vredestein che ha preso parte al tour, alla guida di una Audi Q3 Sportback 45 TFSI E plug-in hybrid dotata di pneumatici all-season Vredestein Quatrac Pro, era composto dalla modella e fashion blogger Gala Gonzalez e da Rachel Zeilic, direttrice creativa dello shop di moda online Majorelle.<\/p>\n<p><a href=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-19492\" src=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito.jpg\" alt=\"Apollo Tyres sostiene Cash &amp; Rocket\" width=\"1800\" height=\"1200\" srcset=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-200x133.jpg 200w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-300x200.jpg 300w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-400x267.jpg 400w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-600x400.jpg 600w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-768x512.jpg 768w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-800x533.jpg 800w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-1024x683.jpg 1024w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-1200x800.jpg 1200w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito-1536x1024.jpg 1536w, https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-2_sito.jpg 1800w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/p>\n<p>Benoit Rivallant, Presidente e CEO di Apollo Tyres Europe, ha dichiarato: &#8220;Cash &amp; Rocket \u00e8 una fantastica organizzazione: stanno facendo un lavoro straordinario per sensibilizzare e raccogliere fondi per cause davvero meritevoli. Ora che al tour prendono parte veicoli con alimentazioni sostenibili, \u00e8 il momento giusto per presentare il marchio Vredestein, che si sta evolvendo per una nuova era della mobilit\u00e0 elettrica. L&#8217;entusiasmo di tutte le persone coinvolte \u00e8 davvero stimolante ed \u00e8 stato emozionante poter contribuire al grande successo di questo evento&#8221;.<\/p>\n<p>Julie Brangstrup Watts, fondatrice di Cash &amp; Rocket, ha commentato: &#8220;\u00c8 stato un piacere avere il marchio Vredestein come sponsor del tour di quest&#8217;anno, il pi\u00f9 grande ed entusiasmante mai realizzato. Abbiamo avuto la fortuna di poter contare su un gruppo davvero stimolante di donne di talento e carattere che ci hanno sostenuto con la loro partecipazione, dimostrando l&#8217;importanza dell&#8217;uguaglianza e della sostenibilit\u00e0&#8221;.<\/p>\n<p>Fondata nel 2011, Cash &amp; Rocket \u00e8 stata creata con il proposito di stimolare il cambiamento motivando e sostenendo donne e bambini bisognosi in tutto il mondo. L&#8217;organizzazione benefica e il tour sono spalleggiati da una serie di influenti personalit\u00e0 femminili.<\/p>\n<p>Per ulteriori informazioni sui prodotti Vredestein, visitare il sito Web all&#8217;indirizzo: <a href=\"https:\/\/www.vredestein.it\/\">vredestein.it<\/a>.<\/p>\n<p>Per ulteriori informazioni su Cash &amp; Rocket, visitare il sito Web all&#8217;indirizzo: <a href=\"http:\/\/www.cashandrocket.com\/\">cashandrocket.com<\/a> e per effettuare donazioni <a href=\"https:\/\/www.cashandrocket.com\/the-tour\">cashandrocket.com\/the-tour\/<\/a><\/p>\n<p><a href=\"https:\/\/www.anicecommunication.it\/Apollo\/220627\/220627_Apollo_Vredestein_Cash_Rocket.zip\">Scarica testo e immagini&gt;&gt;<\/a><\/p>\n<p><a href=\"https:\/\/www.anicecommunication.com\/it\/media-relations\/\">Anicecommunication Ufficio Stampa Apollo Tyres | Vredestein Italia<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &amp; Rocket, volto a promuovere l&#8217;uguaglianza attraverso l&#8217;istruzione<\/p>\n","protected":false},"author":1,"featured_media":19493,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[608,467,80],"tags":[978,979,980],"class_list":["post-19491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apollo-vredestein","category-press_room","category-blog-anicecommunication","tag-apollo-tyres-cash-rocket","tag-vredestein-apollo-tyres","tag-vredestein-e-cash-rocket"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apollo Tyres sostiene il tour dell&#039;organizzazione benefica Cash &amp; Rocket<\/title>\n<meta name=\"description\" content=\"Apollo Tyres sostiene il tour dell&#039;organizzazione benefica Cash &amp; Rocket, volto a promuovere l&#039;uguaglianza attraverso l&#039;istruzione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apollo Tyres sostiene il tour dell&#039;organizzazione benefica Cash &amp; Rocket\" \/>\n<meta property=\"og:description\" content=\"Apollo Tyres sostiene il tour dell&#039;organizzazione benefica Cash &amp; Rocket, volto a promuovere l&#039;uguaglianza attraverso l&#039;istruzione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/\" \/>\n<meta property=\"og:site_name\" content=\"IT Anice | Agenzia di ufficio stampa, PR e media relations specializzata in mobility e automotive practices. Agenzia di comunicazione integrata internazionale a Torino, Parigi, Amsterdam, Francoforte, Madrid, Londra e Goteborg. Anicecommunication\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anicecommunication\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/anicecommunication\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T08:44:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T10:19:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editorial Staff\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editorial Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/\"},\"author\":{\"name\":\"Editorial Staff\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/#\\\/schema\\\/person\\\/d8f9046f11c2ab1ff15f1d0d580184d8\"},\"headline\":\"Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &#038; Rocket\",\"datePublished\":\"2022-06-27T08:44:41+00:00\",\"dateModified\":\"2026-06-16T10:19:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/\"},\"wordCount\":572,\"image\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Cash-Rocket-Vredestein-1_sito.jpg\",\"keywords\":[\"Apollo Tyres Cash &amp; Rocket\",\"Vredestein Apollo Tyres\",\"Vredestein e Cash &amp; Rocket\"],\"articleSection\":[\"Apollo Tyres | Vredestein\",\"Press Room\",\"What A Nice Blog!\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/\",\"url\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/\",\"name\":\"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Cash-Rocket-Vredestein-1_sito.jpg\",\"datePublished\":\"2022-06-27T08:44:41+00:00\",\"dateModified\":\"2026-06-16T10:19:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/#\\\/schema\\\/person\\\/d8f9046f11c2ab1ff15f1d0d580184d8\"},\"description\":\"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket, volto a promuovere l'uguaglianza attraverso l'istruzione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Cash-Rocket-Vredestein-1_sito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/Cash-Rocket-Vredestein-1_sito.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Apollo Tyres sostiene Cash & Rocket\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &#038; Rocket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/\",\"name\":\"Agenzia di ufficio stampa, PR e media relations specializzata in mobility e automotive practices. Agenzia di comunicazione integrata internazionale a Torino, Parigi, Amsterdam, Francoforte, Madrid, Londra e Goteborg. Anicecommunication\",\"description\":\"Anicecommunication agenzia di pubbliche relazioni,  ufficio stampa, media relations, automotive e mobility a livello internazionale - Torino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.anicecommunication.com\\\/it\\\/#\\\/schema\\\/person\\\/d8f9046f11c2ab1ff15f1d0d580184d8\",\"name\":\"Editorial Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g\",\"caption\":\"Editorial Staff\"},\"description\":\"La redazione di Anicecommunication \u00e8 composta da giornalisti, esperti di comunicazione e marketing, content manager e storyteller.\",\"sameAs\":[\"http:\\\/\\\/www.anicecommunication.com\",\"https:\\\/\\\/www.facebook.com\\\/anicecommunication\",\"https:\\\/\\\/x.com\\\/anicecom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket","description":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket, volto a promuovere l'uguaglianza attraverso l'istruzione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/","og_locale":"it_IT","og_type":"article","og_title":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket","og_description":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket, volto a promuovere l'uguaglianza attraverso l'istruzione","og_url":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/","og_site_name":"IT Anice | Agenzia di ufficio stampa, PR e media relations specializzata in mobility e automotive practices. Agenzia di comunicazione integrata internazionale a Torino, Parigi, Amsterdam, Francoforte, Madrid, Londra e Goteborg. Anicecommunication","article_publisher":"https:\/\/www.facebook.com\/anicecommunication","article_author":"https:\/\/www.facebook.com\/anicecommunication","article_published_time":"2022-06-27T08:44:41+00:00","article_modified_time":"2026-06-16T10:19:35+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg","type":"image\/jpeg"}],"author":"Editorial Staff","twitter_misc":{"Scritto da":"Editorial Staff","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#article","isPartOf":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/"},"author":{"name":"Editorial Staff","@id":"https:\/\/www.anicecommunication.com\/it\/#\/schema\/person\/d8f9046f11c2ab1ff15f1d0d580184d8"},"headline":"Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &#038; Rocket","datePublished":"2022-06-27T08:44:41+00:00","dateModified":"2026-06-16T10:19:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/"},"wordCount":572,"image":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg","keywords":["Apollo Tyres Cash &amp; Rocket","Vredestein Apollo Tyres","Vredestein e Cash &amp; Rocket"],"articleSection":["Apollo Tyres | Vredestein","Press Room","What A Nice Blog!"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/","url":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/","name":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket","isPartOf":{"@id":"https:\/\/www.anicecommunication.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#primaryimage"},"image":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg","datePublished":"2022-06-27T08:44:41+00:00","dateModified":"2026-06-16T10:19:35+00:00","author":{"@id":"https:\/\/www.anicecommunication.com\/it\/#\/schema\/person\/d8f9046f11c2ab1ff15f1d0d580184d8"},"description":"Apollo Tyres sostiene il tour dell'organizzazione benefica Cash & Rocket, volto a promuovere l'uguaglianza attraverso l'istruzione","breadcrumb":{"@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#primaryimage","url":"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg","contentUrl":"https:\/\/www.anicecommunication.com\/it\/wp-content\/uploads\/sites\/3\/2022\/06\/Cash-Rocket-Vredestein-1_sito.jpg","width":1800,"height":1200,"caption":"Apollo Tyres sostiene Cash & Rocket"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anicecommunication.com\/it\/apollo-tyres-sostiene-il-tour-dellorganizzazione-benefica-cash-rocket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anicecommunication.com\/it\/"},{"@type":"ListItem","position":2,"name":"Apollo Tyres sostiene il tour dell&#8217;organizzazione benefica Cash &#038; Rocket"}]},{"@type":"WebSite","@id":"https:\/\/www.anicecommunication.com\/it\/#website","url":"https:\/\/www.anicecommunication.com\/it\/","name":"Agenzia di ufficio stampa, PR e media relations specializzata in mobility e automotive practices. Agenzia di comunicazione integrata internazionale a Torino, Parigi, Amsterdam, Francoforte, Madrid, Londra e Goteborg. Anicecommunication","description":"Anicecommunication agenzia di pubbliche relazioni,  ufficio stampa, media relations, automotive e mobility a livello internazionale - Torino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anicecommunication.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.anicecommunication.com\/it\/#\/schema\/person\/d8f9046f11c2ab1ff15f1d0d580184d8","name":"Editorial Staff","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62128a8e64953c282b330a12e5b592d8bc5d299b46ab0e6928129ae0d79e528a?s=96&d=mm&r=g","caption":"Editorial Staff"},"description":"La redazione di Anicecommunication \u00e8 composta da giornalisti, esperti di comunicazione e marketing, content manager e storyteller.","sameAs":["http:\/\/www.anicecommunication.com","https:\/\/www.facebook.com\/anicecommunication","https:\/\/x.com\/anicecom"]}]}},"_links":{"self":[{"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/posts\/19491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/comments?post=19491"}],"version-history":[{"count":1,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/posts\/19491\/revisions"}],"predecessor-version":[{"id":19494,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/posts\/19491\/revisions\/19494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/media\/19493"}],"wp:attachment":[{"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/media?parent=19491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/categories?post=19491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anicecommunication.com\/it\/wp-json\/wp\/v2\/tags?post=19491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}